{"id":29166,"date":"2015-02-19T09:48:19","date_gmt":"2015-02-19T09:48:19","guid":{"rendered":"https:\/\/genova-living.com\/kontaktiere-uns\/"},"modified":"2022-03-20T16:06:12","modified_gmt":"2022-03-20T16:06:12","slug":"kontaktiere-uns","status":"publish","type":"page","link":"https:\/\/genova-living.com\/de\/kontaktiere-uns\/","title":{"rendered":"Kontakt"},"content":{"rendered":"<p style=\"text-align: center;\">Ob Sie ein Einfamilienhaus, ein Ferienhaus oder eine Anlageimmobilie suchen, wir helfen Ihnen, Ihre Traumimmobilie in G\u00e9nova und Umgebung zu finden.<\/p>\n<p style=\"text-align: center;\">Als Partneragentur von <strong>El Terreno Immo<\/strong> sind wir die Experten f\u00fcr Immobilien zwischen El Terreno und Genua. Sprechen Sie uns gerne jederzeit an!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ob Sie ein Einfamilienhaus, ein Ferienhaus oder eine Anlageimmobilie suchen, wir helfen Ihnen, Ihre Traumimmobilie in G\u00e9nova und Umgebung zu finden. Als Partneragentur von El Terreno Immo sind wir die Experten f\u00fcr Immobilien zwischen El Terreno und Genua. Sprechen Sie uns gerne jederzeit an!<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"contact_page.php","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-29166","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ob Sie ein Einfamilienhaus, ein Ferienhaus oder eine Anlageimmobilie suchen, wir helfen Ihnen, Ihre Traumimmobilie in G\u00e9nova und Umgebung zu finden. Als Partneragentur von El Terreno Immo sind wir die Experten f\u00fcr Immobilien zwischen El Terreno und Genua. Sprechen Sie uns gerne jederzeit an!\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/genova-living.com\/de\/kontaktiere-uns\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Genova Living - Immobilienexperten in Genova, Mallorca\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Kontakt - Genova Living\" \/>\n\t\t<meta property=\"og:description\" content=\"Ob Sie ein Einfamilienhaus, ein Ferienhaus oder eine Anlageimmobilie suchen, wir helfen Ihnen, Ihre Traumimmobilie in G\u00e9nova und Umgebung zu finden. Als Partneragentur von El Terreno Immo sind wir die Experten f\u00fcr Immobilien zwischen El Terreno und Genua. Sprechen Sie uns gerne jederzeit an!\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/genova-living.com\/de\/kontaktiere-uns\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-02-19T09:48:19+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-03-20T16:06:12+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Kontakt - Genova Living\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Ob Sie ein Einfamilienhaus, ein Ferienhaus oder eine Anlageimmobilie suchen, wir helfen Ihnen, Ihre Traumimmobilie in G\u00e9nova und Umgebung zu finden. Als Partneragentur von El Terreno Immo sind wir die Experten f\u00fcr Immobilien zwischen El Terreno und Genua. Sprechen Sie uns gerne jederzeit an!\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/genova-living.com\\\/de\\\/kontaktiere-uns\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/genova-living.com\\\/de\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/genova-living.com\\\/de\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/genova-living.com\\\/de\\\/kontaktiere-uns\\\/#listItem\",\"name\":\"Kontakt\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/genova-living.com\\\/de\\\/kontaktiere-uns\\\/#listItem\",\"position\":2,\"name\":\"Kontakt\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/genova-living.com\\\/de\\\/#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/genova-living.com\\\/de\\\/#organization\",\"name\":\"Genova Living\",\"description\":\"Immobilienexperten in Genova, Mallorca\",\"url\":\"https:\\\/\\\/genova-living.com\\\/de\\\/\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/genova-living.com\\\/de\\\/kontaktiere-uns\\\/#webpage\",\"url\":\"https:\\\/\\\/genova-living.com\\\/de\\\/kontaktiere-uns\\\/\",\"name\":\"Kontakt - Genova Living\",\"description\":\"Ob Sie ein Einfamilienhaus, ein Ferienhaus oder eine Anlageimmobilie suchen, wir helfen Ihnen, Ihre Traumimmobilie in G\\u00e9nova und Umgebung zu finden. Als Partneragentur von El Terreno Immo sind wir die Experten f\\u00fcr Immobilien zwischen El Terreno und Genua. Sprechen Sie uns gerne jederzeit an!\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/genova-living.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/genova-living.com\\\/de\\\/kontaktiere-uns\\\/#breadcrumblist\"},\"datePublished\":\"2015-02-19T09:48:19+00:00\",\"dateModified\":\"2022-03-20T16:06:12+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/genova-living.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/genova-living.com\\\/de\\\/\",\"name\":\"Genova Living\",\"description\":\"Immobilienexperten in Genova, Mallorca\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/genova-living.com\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Kontakt - Genova Living","description":"Ob Sie ein Einfamilienhaus, ein Ferienhaus oder eine Anlageimmobilie suchen, wir helfen Ihnen, Ihre Traumimmobilie in G\u00e9nova und Umgebung zu finden. Als Partneragentur von El Terreno Immo sind wir die Experten f\u00fcr Immobilien zwischen El Terreno und Genua. Sprechen Sie uns gerne jederzeit an!","canonical_url":"https:\/\/genova-living.com\/de\/kontaktiere-uns\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/genova-living.com\/de\/kontaktiere-uns\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/genova-living.com\/de\/#listItem","position":1,"name":"Home","item":"https:\/\/genova-living.com\/de\/","nextItem":{"@type":"ListItem","@id":"https:\/\/genova-living.com\/de\/kontaktiere-uns\/#listItem","name":"Kontakt"}},{"@type":"ListItem","@id":"https:\/\/genova-living.com\/de\/kontaktiere-uns\/#listItem","position":2,"name":"Kontakt","previousItem":{"@type":"ListItem","@id":"https:\/\/genova-living.com\/de\/#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/genova-living.com\/de\/#organization","name":"Genova Living","description":"Immobilienexperten in Genova, Mallorca","url":"https:\/\/genova-living.com\/de\/"},{"@type":"WebPage","@id":"https:\/\/genova-living.com\/de\/kontaktiere-uns\/#webpage","url":"https:\/\/genova-living.com\/de\/kontaktiere-uns\/","name":"Kontakt - Genova Living","description":"Ob Sie ein Einfamilienhaus, ein Ferienhaus oder eine Anlageimmobilie suchen, wir helfen Ihnen, Ihre Traumimmobilie in G\u00e9nova und Umgebung zu finden. Als Partneragentur von El Terreno Immo sind wir die Experten f\u00fcr Immobilien zwischen El Terreno und Genua. Sprechen Sie uns gerne jederzeit an!","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/genova-living.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/genova-living.com\/de\/kontaktiere-uns\/#breadcrumblist"},"datePublished":"2015-02-19T09:48:19+00:00","dateModified":"2022-03-20T16:06:12+00:00"},{"@type":"WebSite","@id":"https:\/\/genova-living.com\/de\/#website","url":"https:\/\/genova-living.com\/de\/","name":"Genova Living","description":"Immobilienexperten in Genova, Mallorca","inLanguage":"de-DE","publisher":{"@id":"https:\/\/genova-living.com\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Genova Living - Immobilienexperten in Genova, Mallorca","og:type":"article","og:title":"Kontakt - Genova Living","og:description":"Ob Sie ein Einfamilienhaus, ein Ferienhaus oder eine Anlageimmobilie suchen, wir helfen Ihnen, Ihre Traumimmobilie in G\u00e9nova und Umgebung zu finden. Als Partneragentur von El Terreno Immo sind wir die Experten f\u00fcr Immobilien zwischen El Terreno und Genua. Sprechen Sie uns gerne jederzeit an!","og:url":"https:\/\/genova-living.com\/de\/kontaktiere-uns\/","article:published_time":"2015-02-19T09:48:19+00:00","article:modified_time":"2022-03-20T16:06:12+00:00","twitter:card":"summary","twitter:title":"Kontakt - Genova Living","twitter:description":"Ob Sie ein Einfamilienhaus, ein Ferienhaus oder eine Anlageimmobilie suchen, wir helfen Ihnen, Ihre Traumimmobilie in G\u00e9nova und Umgebung zu finden. Als Partneragentur von El Terreno Immo sind wir die Experten f\u00fcr Immobilien zwischen El Terreno und Genua. Sprechen Sie uns gerne jederzeit an!"},"aioseo_meta_data":{"post_id":"29166","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"WebPage","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-03-19 12:08:00","updated":"2025-09-25 19:20:18","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/genova-living.com\/de\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tKontakt\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/genova-living.com\/de\/"},{"label":"Kontakt","link":"https:\/\/genova-living.com\/de\/kontaktiere-uns\/"}],"_links":{"self":[{"href":"https:\/\/genova-living.com\/de\/wp-json\/wp\/v2\/pages\/29166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/genova-living.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/genova-living.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/genova-living.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/genova-living.com\/de\/wp-json\/wp\/v2\/comments?post=29166"}],"version-history":[{"count":1,"href":"https:\/\/genova-living.com\/de\/wp-json\/wp\/v2\/pages\/29166\/revisions"}],"predecessor-version":[{"id":32828,"href":"https:\/\/genova-living.com\/de\/wp-json\/wp\/v2\/pages\/29166\/revisions\/32828"}],"wp:attachment":[{"href":"https:\/\/genova-living.com\/de\/wp-json\/wp\/v2\/media?parent=29166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}